{"id":240817,"date":"2022-10-04T12:30:00","date_gmt":"2022-10-04T12:30:00","guid":{"rendered":"https:\/\/bold-cartwright.3-19-126-172.plesk.page\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/"},"modified":"2022-11-18T20:48:58","modified_gmt":"2022-11-18T20:48:58","slug":"linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura","status":"publish","type":"post","link":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/","title":{"rendered":"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>Il lungometraggio dei produttori vincitori dell\u2019Oscar offre alcuni scorci senza precedenti della storia personale di Papa Francesco creando pressione per la giustizia climatica globale, mettendo in luce voci inascoltate che sono in prima linea nella crisi.<\/strong><\/p>\n\n<p><\/p>\n\n<p>Un nuovo documentario sul potere dell\u2019umanit\u00e0 di fermare la crisi ecologica \u00e8 stato presentato oggi in anteprima nella Citt\u00e0 del Vaticano. Intitolato <em>La Lettera<\/em>, il film racconta la storia dei viaggi a Roma di vari leader in prima linea per confrontarsi sull\u2019enciclica Laudato Si\u2019 con Papa Francesco.<\/p>\n\n<p>Il film \u00e8 stato prodotto da <a href=\"https:\/\/www.offthefence.com\/Production\/Home\" target=\"_blank\" rel=\"noreferrer noopener\">Off the Fence<\/a>, produttori vincitori di Oscar<em> <\/em><em>(My Octopus Teacher)<\/em>. Con protagonisti provenienti dall\u2019Amazzonia brasiliana, dal Senegal, dall\u2019India e dagli Stati Uniti, il film esplora questioni come i diritti degli indigeni, la migrazione climatica e la leadership dei giovani nel contesto dell\u2019azione per il clima e la natura. Il film include un dialogo esclusivo con Papa Francesco e immagini inedite del suo insediamento come Papa. <\/p>\n\n<p>All\u2019anteprima del film in Vaticano hanno partecipato i protagonisti e i registi, il pi\u00f9 alto funzionario vaticano per le questioni ecologiche e il segretario generale dell\u2019IPCC, oltre ad ambasciatori e rappresentanti della societ\u00e0 civile.<\/p>\n\n<p>Il film \u00e8 presentato da YouTube Originals. \u00c8 la prima volta che un film con un Papa sar\u00e0 disponibile gratuitamente attraverso un servizio di streaming.<\/p>\n\n<p>L\u2019anteprima avviene nello stesso giorno in cui la Santa Sede entra ufficialmente nell\u2019importante accordo di Parigi sui cambiamenti climatici. Funzionari vaticani hanno ospitato ambasciatori presso la Santa Sede sia all\u2019anteprima che a un evento collaterale di alto livello sull\u2019Accordo di Parigi, facendo pressione sui governi per una maggiore azione sul clima. <\/p>\n\n<p>Questi sforzi rappresentano l\u2019impegno sempre pi\u00f9 ambizioso e urgente della Chiesa cattolica sulle questioni ecologiche. Nei prossimi mesi \u00e8 prevista una campagna globale di proiezioni nelle comunit\u00e0, eventi di alto livello e leadership da parte di organizzazioni partner nel Nord e nel Sud del mondo, che daranno impulso a nuove pressioni sui responsabili delle decisioni al vertice sul clima COP27 e al vertice sulla natura COP15 delle Nazioni Unite. <\/p>\n\n<p>Questa urgenza \u00e8 in linea con gli allarmi lanciati dal Gruppo Intergovernativo di Esperti sul Cambiamento Climatico delle Nazioni Unite, l\u2019organismo scientifico sul clima che ispira l\u2019accordo di Parigi e la COP27. Nel commentare il film, il presidente dell\u2019IPCC presente agli eventi vaticani, il dottor Hoesung Lee, ha dichiarato: \u201cLa comunit\u00e0 scientifica accoglie con favore l\u2019opportunit\u00e0 di confrontarsi con gli artisti e le persone di fede mentre lavoriamo per trovare soluzioni alla crisi climatica\u201d.<\/p>\n\n<p>Ridhima Pandey, giovane attivista per il clima e protagonista di <em>La Lettera<\/em>, ha dichiarato: \u201cGli adulti devono fare meglio. E non ho intenzione di aspettare che voi troviate una soluzione. Credetemi, i miei sforzi sono solo all\u2019inizio. Credetemi, il mio impegno \u00e8 appena iniziato\u201d.<\/p>\n\n<p>Nicolas Brown, regista del film <em>La Lettera<\/em>, ha dichiarato: \u201cGuidati dalla bussola morale fornita da Papa Francesco, mi aspetto che tutti noi possiamo trovare rinnovate motivazioni e impegno nel proteggere la nostra casa comune e nell\u2019avere compassione per tutti gli esseri viventi, compresi gli esseri umani\u201d.<\/p>\n\n<p><\/p>\n\n<p><strong>Informazioni sul film<\/strong><\/p>\n\n<p>Prodotto dal team di <a href=\"https:\/\/www.offthefence.com\/Production\/Home\" target=\"_blank\" rel=\"noreferrer noopener\">Off the Fence<\/a>, vincitore del premio Oscar<em> <\/em>(<em>My Octopus Teacher<\/em>), in partnership con il <a href=\"https:\/\/laudatosimovement.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Movimento Laudato Si\u2018<\/a>, il film \u00e8 stato diretto dal regista vincitore di un Emmy, Nicolas Brown. <em>La Lettera<\/em> \u00e8 stata realizzato in collaborazione con il <a href=\"https:\/\/www.comunicazione.va\/en.html\" target=\"_blank\" rel=\"noreferrer noopener\">Dicastero per la Comunicazione<\/a> e il <a href=\"https:\/\/www.humandevelopment.va\/en.html\" target=\"_blank\" rel=\"noreferrer noopener\">Dicastero per il Servizio dello Sviluppo Umano Integrale<\/a>. Il film \u00e8 presentato da <a href=\"https:\/\/www.youtube.com\/originals\/featured\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube Originals<\/a>.<\/p>\n\n<p>Ulteriori informazioni sul film sono disponibili <a href=\"https:\/\/docs.google.com\/document\/d\/1-qYMqAAjuc_u4pC50reOdwS911m_6tQDKkAGshRHmC4\/edit?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a> e su <a href=\"https:\/\/www1.theletterfilm.org\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">TheLetterFilm.org<\/a>. Risorse <\/p>\n\n<p><\/p>\n\n<p><strong>Risorse<\/strong><\/p>\n\n<p>Brevi biografie e foto dei protagonisti, tra cui Papa Francesco sono disponibili <a href=\"https:\/\/drive.google.com\/drive\/folders\/1dFxgnreYg9YcxYE_by8rOhMX6DYU8Cz0?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a>. Le foto dei protagonisti e dei leader di alto livello presenti agli eventi vaticani saranno disponibili <a href=\"https:\/\/drive.google.com\/drive\/folders\/1eg07q668b2zLK07zwFnGUChJwb6zeCa_?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a> alle 19.00 CEST del 4 ottobre. <\/p>\n\n<p>Il trailer e il film completo sono <a href=\"https:\/\/www.youtube.com\/watch?v=l3EBHebH17Y\" target=\"_blank\" rel=\"noreferrer noopener\">disponibili<\/a> sul canale <a href=\"https:\/\/www.youtube.com\/originals\/videos\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube Originals<\/a>. Il film sar\u00e0 proiettato in diretta il 4 ottobre alle 18.30 CEST.<\/p>\n\n<p><\/p>\n\n<p><strong>Conferenza stampa<\/strong><\/p>\n\n<p>Il 4 ottobre alle 11.30 CEST si terr\u00e0 una conferenza stampa in Sala Stampa con i seguenti relatori:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Cardinale Michael Czerny, Prefetto del Dicastero per il Servizio dello Sviluppo Umano Integrale<\/li>\n\n\n\n<li>Dott. Hoesung Lee, Presidente del Gruppo Intergovernativo di Esperti sul Cambiamento Climatico<\/li>\n\n\n\n<li>Cacique Odair \u201cDad\u00e1\u201d Borari, protagonista del film e Capo Generale del Territorio Indigeno Mar\u00f3, Par\u00e1, Brasile<\/li>\n\n\n\n<li>Dott.ssa Lorna Gold, Presidente del Consiglio di Amministrazione del Movimento Laudato Si\u2019<\/li>\n\n\n\n<li>Nicolas Brown, scrittore e regista, <em>La Lettera<\/em><\/li>\n<\/ul>\n\n<p>I giornalisti accreditati dal Vaticano sono i benvenuti. <\/p>\n\n<p>Coloro che non sono accreditati ma desiderano partecipare di persona, sono pregati di contattare Gabriel L\u00f3pez Santamaria all\u2019indirizzo <a href=\"mailto:gabriel@laudatosimovement.org\" target=\"_blank\" rel=\"noreferrer noopener\">gabriel@laudatosimovement.org<\/a> entro il 3 ottobre alle 12.00 CEST. <\/p>\n\n<p>Per i giornalisti che non sono a Roma, la conferenza stampa sar\u00e0 trasmessa in diretta, disponibile <a href=\"https:\/\/www.youtube.com\/watch?v=39QcvKFFnes\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a> dalle 11.30 CEST. <\/p>\n\n<p><\/p>\n\n<p><strong>Evento di anteprima<\/strong><\/p>\n\n<p>Ambasciatori presso la Santa Sede, scienziati, dirigenti dei media, leader della Chiesa e rappresentanti della societ\u00e0 civile parteciperanno alla proiezione del film nell\u2019Aula del Sinodo Vaticano. <\/p>\n\n<p>Le porte saranno aperte e ci sar\u00e0 una sessione fotografica alle 17.30 CEST. Il film inizier\u00e0 alle 18.30 CEST. Dopo il film si terr\u00e0 un ricevimento.<\/p>\n\n<p>Per partecipare \u00e8 necessaria la registrazione. I giornalisti interessati a partecipare possono registrarsi <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeZ-Mnu8TcK56onGXrXN7r78kcfNHn9gpSbjGeSb_95UcTjVQ\/viewform?usp=sf_link\" target=\"_blank\" rel=\"noreferrer noopener\">qui<\/a>. <\/p>\n\n<p><\/p>\n\n<p><strong>Interviste<\/strong><\/p>\n\n<p>I protagonisti del film, il Cardinale Czerny, il Segretario Lee e il regista Nicolas Brown, saranno disponibili per interviste e foto di persona subito dopo la conferenza stampa, dalle 12.30 alle 13.30 circa, in Sala Stampa. <\/p>\n\n<p>Prima della conferenza stampa sono disponibili interviste scritte. Si prega di inviare le domande a Gabriel L\u00f3pez Santamaria all\u2019indirizzo <a href=\"mailto:gabriel@laudatosimovement.org\" target=\"_blank\" rel=\"noreferrer noopener\">gabriel@laudatosimovement.org<\/a> entro il 2 ottobre alle 12.00 CEST.<\/p>\n\n<p>Sono disponibili i commenti di portavoce.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Movimento Laudato Si\u2019: contattare Gabriel L\u00f3pez Santamaria all\u2019indirizzo <a href=\"mailto:gabriel@laudatosimovement.org\" target=\"_blank\" rel=\"noreferrer noopener\">gabriel@laudatosimovement.org<\/a>.<\/li>\n\n\n\n<li>Off the Fence Productions: contattare Nicolas Brown, scrittore e regista, <em>La Lettera<\/em>, all\u2019indirizzo <a href=\"mailto:nicolasrbrown@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">nicolasrbrown@gmail.com<\/a>.<\/li>\n<\/ul>\n\n<p><\/p>\n\n<p><strong>Dichiarazioni dei leader, protagonisti e regista<\/strong><\/p>\n\n<p><em>Leader<\/em><\/p>\n\n<p>Il cardinale Michael Czerny, prefetto del Dicastero per il Servizio dello Sviluppo Umano Integrale, ha dichiarato:<em> <\/em>\u201cNella sua enciclica Laudato Si\u2019 Papa Francesco desidera entrare in dialogo con tutte le persone sul pianeta Terra, la nostra casa comune. La crisi ambientale non \u00e8 un problema che riguarda solo i cattolici. Riguarda tutti, ora e per le generazioni future. Questo film \u00e8 un grido d\u2019allarme per le persone di tutto il mondo: dobbiamo agire insieme, e dobbiamo farlo ora\u201d.<\/p>\n\n<p>Il dottor Hoesung Lee, presidente del Gruppo Intergovernativo di Esperti sul Cambiamento Climatico, ha dichiarato: \u201cLa sfida del cambiamento climatico \u00e8 globale e la scienza \u00e8 chiara. Il momento di agire \u00e8 adesso\u201d. Il dottor Lee ha continuato: \u201cLa comunit\u00e0 scientifica accoglie con favore l\u2019opportunit\u00e0 di confrontarsi con artisti e persone di fede. Sia la fede che l\u2019arte hanno un grande potere di convocazione e possono ispirare un\u2019autentica azione collettiva per il clima\u201d.<\/p>\n\n<p><em>Protagonisti<\/em><\/p>\n\n<p>La dott.ssa Lorna Gold, Presidente del Movimento Laudato Si\u2019, ha dichiarato: \u201cI segni della catastrofe ecologica sono ovunque, eppure ancora non ce ne accorgiamo. Questo film bellissimo e stimolante mette in luce le tragiche conseguenze dell\u2019inazione, ma indica anche la strada da seguire. Grazie a questo film, siamo andati oltre le cose che sembrano separarci come persone provenienti da contesti cos\u00ec diversi. Abbiamo scoperto che ci\u00f2 che ci unisce \u00e8 un senso di umanit\u00e0 condivisa, di essere una famiglia. Questo mi fa sperare per la nostra casa comune\u201d.<\/p>\n\n<p>Il dottor Greg Asner, direttore del Center for Global Discovery and Conservation Science dell\u2019Arizona State University e coautore della tecnologia Spectranomics per la creazione di mappe 3D della biodiversit\u00e0, ha dichiarato: \u201cLa scienza dimostra che il pianeta sta cambiando troppo velocemente perch\u00e9 gran parte della vita possa tenere il passo. Dalle catastrofiche ondate di calore negli oceani alla siccit\u00e0 sulla terraferma, la Terra ci dice continuamente che abbiamo spinto il nostro pianeta troppo in l\u00e0. Dobbiamo trasformare la preoccupazione in un\u2019azione rapida. Non sono solo le piante e gli animali ad essere in pericolo: anche noi dipendiamo dal pianeta e dalla sua biodiversit\u00e0 per sopravvivere e prosperare\u201d.<\/p>\n\n<p>Cacique Odair \u201cDad\u00e1\u201d Borari, Capo Generale del Territorio Indigeno Mar\u00f3 nel Par\u00e1, ha dichiarato: \u201cProteggere l\u2019Amazzonia e la sua gente \u00e8 il mio lavoro. Lo faccio ogni giorno da decenni. Le persone che vogliono distruggere l\u2019Amazzonia mi hanno attaccato, ma io non mi arrendo. Proteggo la terra dei miei antenati e lo spirito della vita in essa. Ma questa lotta non \u00e8 solo mia. La protezione dell\u2019Amazzonia dipende da tutti noi\u201d. <\/p>\n\n<p>Arouna Kand\u00e9, rifugiato climatico e studente di sviluppo sostenibile, ha dichiarato: \u201cLa mia famiglia in Senegal non ha fatto nulla per causare la siccit\u00e0 nel nostro villaggio o le inondazioni in citt\u00e0. Come chiarisce questo film, conviviamo con le scelte fatte da altre persone. Ma il futuro sta arrivando, \u00e8 mio e lo guider\u00f2 bene. Studio all\u2019universit\u00e0, pianto alberi e cerco di aiutare la mia gente a vivere e crescere in modo sostenibile. Il Senegal ha la creativit\u00e0 e l\u2019ingegno per guidare il futuro in modo pi\u00f9 equo. Ne far\u00f2 parte e far\u00f2 meglio di quanto loro abbiano fatto con me\u201d. <\/p>\n\n<p>Ridhima Pandey, giovane attivista per il clima, ha dichiarato: \u201cPer la mia generazione, vedere il paesaggio cambiare in modo incredibile \u00e8 diventato quasi un luogo comune. Da bambina avevo degli incubi sulle inondazioni estreme nel mio paese. Mi preoccupa che questi incubi diventino la realt\u00e0 vissuta dai bambini in India. E ora alle inondazioni si aggiungono le ondate di calore. Noi giovani stiamo dicendo basta. Gli adulti devono fare meglio .E non ho intenzione di aspettare che voi troviate una soluzione. Credetemi, i miei sforzi sono solo all\u2019inizio\u201d.<\/p>\n\n<p>Dott.ssa Robin Martin, Professoressa presso l\u2019Arizona State University e coautrice della tecnologia Spectranomics per la creazione di mappe 3D della biodiversit\u00e0, ha dichiarato: \u201cQuando ho incontrato Papa Francesco mentre stavamo girando questo film, gli ho dato una conchiglia di ciprea all\u2019interno di una scatola di legno di koa, tutto proveniente dalla mia isola natale nelle Hawaii. Il cowry, leho in hawaiano, \u00e8 un simbolo di protezione e veniva usato anche come moneta e come semplice spuntino che poteva sostentare durante un viaggio lungo la costa. Il koa \u00e8 il pi\u00f9 grande degli alberi nativi delle Hawaii ed \u00e8 molto ricercato per la costruzione di canoe da viaggio. La natura non \u00e8 solo qualcosa da studiare. Tutte le cose hanno una bellezza, una storia e uno scopo da custodire e valorizzare a pieno titolo\u201d.<\/p>\n\n<p><em>Regista<\/em><\/p>\n\n<p>Mr. Nicolas Brown, regista de <em>La Lettera<\/em>, ha dichiarato: \u201cAffrontare il duplice problema del cambiamento climatico e della perdita di biodiversit\u00e0 \u00e8 la sfida pi\u00f9 seria che l\u2019umanit\u00e0 abbia mai affrontato. \u00c8 facile perdere la speranza. Ma oggi sono pieno di nuovo entusiasmo per le persone che si sono unite per realizzare \u201cLa Lettera\u201d. Scommetto che le loro storie vi ispireranno come hanno fatto con me. E guidati dalla bussola morale fornita da Papa Francesco, spero che tutti noi possiamo trovare rinnovate motivazioni e impegno per proteggere la nostra casa comune e avere compassione per tutti gli esseri viventi, compresi gli esseri umani\u201d.<\/p>\n\n<p><\/p>\n\n<p><strong>Contatto per i media: Gabriel L\u00f3pez Santamaria, <a href=\"mailto:gabriel@laudatosimovement.org\">gabriel@laudatosimovement.org<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo documentario sul potere dell&#8217;umanit\u00e0 di fermare la crisi ecologica \u00e8 stato presentato oggi in anteprima nella Citt\u00e0 del Vaticano.<\/p>\n","protected":false},"author":2,"featured_media":240502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[76],"tags":[],"class_list":["post-240817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura - The Letter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura - The Letter\" \/>\n<meta property=\"og:description\" content=\"Un nuovo documentario sul potere dell&#039;umanit\u00e0 di fermare la crisi ecologica \u00e8 stato presentato oggi in anteprima nella Citt\u00e0 del Vaticano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/\" \/>\n<meta property=\"og:site_name\" content=\"The Letter\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100085611172060\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-04T12:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-18T20:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theletterfilm.org\/wp-content\/uploads\/2022\/10\/LAUDATO-SI_12-scaled-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The Letter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Letter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/\"},\"author\":{\"name\":\"The Letter\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#\\\/schema\\\/person\\\/79cff1a6d5df6a02d56555cc24633bcf\"},\"headline\":\"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura\",\"datePublished\":\"2022-10-04T12:30:00+00:00\",\"dateModified\":\"2022-11-18T20:48:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/\"},\"wordCount\":1826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/theletterfilm.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAUDATO-SI_12-scaled-1.jpeg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/\",\"url\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/\",\"name\":\"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura - The Letter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/theletterfilm.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAUDATO-SI_12-scaled-1.jpeg\",\"datePublished\":\"2022-10-04T12:30:00+00:00\",\"dateModified\":\"2022-11-18T20:48:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/theletterfilm.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAUDATO-SI_12-scaled-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/theletterfilm.org\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/LAUDATO-SI_12-scaled-1.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/2022\\\/10\\\/04\\\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#website\",\"url\":\"https:\\\/\\\/theletterfilm.org\\\/\",\"name\":\"The Letter\",\"description\":\"Act Now\",\"publisher\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/theletterfilm.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#organization\",\"name\":\"The Letter Film\",\"url\":\"https:\\\/\\\/theletterfilm.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www1.theletterfilm.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/EN_Letter0.png\",\"contentUrl\":\"https:\\\/\\\/www1.theletterfilm.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/EN_Letter0.png\",\"width\":854,\"height\":214,\"caption\":\"The Letter Film\"},\"image\":{\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100085611172060\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/theletterfilm.org\\\/#\\\/schema\\\/person\\\/79cff1a6d5df6a02d56555cc24633bcf\",\"name\":\"The Letter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"The Letter\"},\"url\":\"https:\\\/\\\/theletterfilm.org\\\/it\\\/author\\\/the-letter\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura - The Letter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura - The Letter","og_description":"Un nuovo documentario sul potere dell'umanit\u00e0 di fermare la crisi ecologica \u00e8 stato presentato oggi in anteprima nella Citt\u00e0 del Vaticano.","og_url":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/","og_site_name":"The Letter","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100085611172060","article_published_time":"2022-10-04T12:30:00+00:00","article_modified_time":"2022-11-18T20:48:58+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/theletterfilm.org\/wp-content\/uploads\/2022\/10\/LAUDATO-SI_12-scaled-1.jpeg","type":"image\/jpeg"}],"author":"The Letter","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"The Letter","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#article","isPartOf":{"@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/"},"author":{"name":"The Letter","@id":"https:\/\/theletterfilm.org\/#\/schema\/person\/79cff1a6d5df6a02d56555cc24633bcf"},"headline":"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura","datePublished":"2022-10-04T12:30:00+00:00","dateModified":"2022-11-18T20:48:58+00:00","mainEntityOfPage":{"@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/"},"wordCount":1826,"commentCount":0,"publisher":{"@id":"https:\/\/theletterfilm.org\/#organization"},"image":{"@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#primaryimage"},"thumbnailUrl":"https:\/\/theletterfilm.org\/wp-content\/uploads\/2022\/10\/LAUDATO-SI_12-scaled-1.jpeg","articleSection":["Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/","url":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/","name":"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura - The Letter","isPartOf":{"@id":"https:\/\/theletterfilm.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#primaryimage"},"image":{"@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#primaryimage"},"thumbnailUrl":"https:\/\/theletterfilm.org\/wp-content\/uploads\/2022\/10\/LAUDATO-SI_12-scaled-1.jpeg","datePublished":"2022-10-04T12:30:00+00:00","dateModified":"2022-11-18T20:48:58+00:00","breadcrumb":{"@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#primaryimage","url":"https:\/\/theletterfilm.org\/wp-content\/uploads\/2022\/10\/LAUDATO-SI_12-scaled-1.jpeg","contentUrl":"https:\/\/theletterfilm.org\/wp-content\/uploads\/2022\/10\/LAUDATO-SI_12-scaled-1.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/theletterfilm.org\/it\/2022\/10\/04\/linnovativo-documentario-di-youtube-originals-con-papa-francesco-da-nuovo-impulso-allazione-sul-clima-e-la-natura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/theletterfilm.org\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019innovativo documentario di YouTube Originals con Papa Francesco d\u00e0 nuovo impulso all\u2019azione sul clima e la natura"}]},{"@type":"WebSite","@id":"https:\/\/theletterfilm.org\/#website","url":"https:\/\/theletterfilm.org\/","name":"The Letter","description":"Act Now","publisher":{"@id":"https:\/\/theletterfilm.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theletterfilm.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/theletterfilm.org\/#organization","name":"The Letter Film","url":"https:\/\/theletterfilm.org\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/theletterfilm.org\/#\/schema\/logo\/image\/","url":"https:\/\/www1.theletterfilm.org\/wp-content\/uploads\/2020\/09\/EN_Letter0.png","contentUrl":"https:\/\/www1.theletterfilm.org\/wp-content\/uploads\/2020\/09\/EN_Letter0.png","width":854,"height":214,"caption":"The Letter Film"},"image":{"@id":"https:\/\/theletterfilm.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100085611172060"]},{"@type":"Person","@id":"https:\/\/theletterfilm.org\/#\/schema\/person\/79cff1a6d5df6a02d56555cc24633bcf","name":"The Letter","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"The Letter"},"url":"https:\/\/theletterfilm.org\/it\/author\/the-letter\/"}]}},"_links":{"self":[{"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/posts\/240817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/comments?post=240817"}],"version-history":[{"count":0,"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/posts\/240817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/media\/240502"}],"wp:attachment":[{"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/media?parent=240817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/categories?post=240817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theletterfilm.org\/it\/wp-json\/wp\/v2\/tags?post=240817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}